﻿{"id":44205,"date":"2025-11-03T10:32:01","date_gmt":"2025-11-03T09:32:01","guid":{"rendered":"http:\/\/www.sma.unipr.it\/?post_type=tribe_events&#038;p=44205"},"modified":"2025-11-11T09:12:17","modified_gmt":"2025-11-11T08:12:17","slug":"gran-folla-al-must-debutto-da-record-per-il-museo-di-storiografia-naturalistica-dellateneo","status":"publish","type":"tribe_events","link":"http:\/\/www.sma.unipr.it\/it\/event\/gran-folla-al-must-debutto-da-record-per-il-museo-di-storiografia-naturalistica-dellateneo\/","title":{"rendered":"Gran folla al MUST: debutto da record per il Museo di Storiografia Naturalistica dell\u2019Ateneo"},"content":{"rendered":"<p>Davvero un gran debutto per il MUST, il\u00a0<strong>Museo di Storiografia Naturalistica dell\u2019Universit\u00e0 di Parma<\/strong>. Dopo le prime due giornate solo su prenotazione, oggi l\u2019apertura a ingresso libero \u00e8 stata da tutto esaurito. Gran folla fin dall\u2019apertura, alle 10, e poi per tutto l\u2019arco della giornata. Da parte delle visitatrici e dei visitatori grande apprezzamento per il nuovo museo, che intreccia storiografia e mondo naturale secondo un approccio moderno, immersivo, sensoriale e inclusivo: un grande racconto naturalistico\u00a0che segue la linea del tempo attraverso le vite e le collezioni dei suoi protagonisti.<\/p>\n<p>Il <a href=\"https:\/\/www.sma.unipr.it\/it\/museo-di-storiografia-naturalistica\/\">MUST<\/a> \u00e8 aperto dal marted\u00ec al venerd\u00ec ore 10 &#8211; 17 (<strong>ultimo ingresso ore 16)<\/strong> e il sabato ore 10-18 (<strong>ultimo ingresso ore 17)<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Davvero un gran debutto per il MUST, il\u00a0Museo di Storiografia Naturalistica dell\u2019Universit\u00e0 di Parma. Dopo le prime due giornate solo su prenotazione, oggi l\u2019apertura a ingresso libero \u00e8 stata da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":44222,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[139,74,42],"class_list":["post-44205","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-museo-di-storiografia-naturalistica","tribe_events_cat-news","tribe_events_cat-sede-centrale-delluniversita","cat_museo-di-storiografia-naturalistica","cat_news","cat_sede-centrale-delluniversita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gran folla al MUST: debutto da record per il Museo di Storiografia Naturalistica dell\u2019Ateneo - Sistema Museale di Ateneo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.sma.unipr.it\/it\/event\/gran-folla-al-must-debutto-da-record-per-il-museo-di-storiografia-naturalistica-dellateneo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gran folla al MUST: debutto da record per il Museo di Storiografia Naturalistica dell\u2019Ateneo - Sistema Museale di Ateneo\" \/>\n<meta property=\"og:description\" content=\"Davvero un gran debutto per il MUST, il\u00a0Museo di Storiografia Naturalistica dell\u2019Universit\u00e0 di Parma. Dopo le prime due giornate solo su prenotazione, oggi l\u2019apertura a ingresso libero \u00e8 stata da [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.sma.unipr.it\/it\/event\/gran-folla-al-must-debutto-da-record-per-il-museo-di-storiografia-naturalistica-dellateneo\/\" \/>\n<meta property=\"og:site_name\" content=\"Sistema Museale di Ateneo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MEMAunipr\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-11T08:12:17+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.sma.unipr.it\/wp-content\/uploads\/2025\/11\/MUST-wunderkammer-farfalle-imamgine-in-evidenza-1030x687.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1030\" \/>\n\t<meta property=\"og:image:height\" content=\"687\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.sma.unipr.it\\\/it\\\/event\\\/gran-folla-al-must-debutto-da-record-per-il-museo-di-storiografia-naturalistica-dellateneo\\\/\",\"url\":\"http:\\\/\\\/www.sma.unipr.it\\\/it\\\/event\\\/gran-folla-al-must-debutto-da-record-per-il-museo-di-storiografia-naturalistica-dellateneo\\\/\",\"name\":\"Gran folla al MUST: debutto da record per il Museo di Storiografia Naturalistica dell\u2019Ateneo - Sistema Museale di Ateneo\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.sma.unipr.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.sma.unipr.it\\\/it\\\/event\\\/gran-folla-al-must-debutto-da-record-per-il-museo-di-storiografia-naturalistica-dellateneo\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.sma.unipr.it\\\/it\\\/event\\\/gran-folla-al-must-debutto-da-record-per-il-museo-di-storiografia-naturalistica-dellateneo\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.sma.unipr.it\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/MUST-wunderkammer-farfalle-imamgine-in-evidenza.png\",\"datePublished\":\"2025-11-03T09:32:01+00:00\",\"dateModified\":\"2025-11-11T08:12:17+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.sma.unipr.it\\\/it\\\/event\\\/gran-folla-al-must-debutto-da-record-per-il-museo-di-storiografia-naturalistica-dellateneo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.sma.unipr.it\\\/it\\\/event\\\/gran-folla-al-must-debutto-da-record-per-il-museo-di-storiografia-naturalistica-dellateneo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.sma.unipr.it\\\/it\\\/event\\\/gran-folla-al-must-debutto-da-record-per-il-museo-di-storiografia-naturalistica-dellateneo\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.sma.unipr.it\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/MUST-wunderkammer-farfalle-imamgine-in-evidenza.png\",\"contentUrl\":\"http:\\\/\\\/www.sma.unipr.it\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/MUST-wunderkammer-farfalle-imamgine-in-evidenza.png\",\"width\":1200,\"height\":800,\"caption\":\"MUST wunderkammer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.sma.unipr.it\\\/it\\\/event\\\/gran-folla-al-must-debutto-da-record-per-il-museo-di-storiografia-naturalistica-dellateneo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/www.sma.unipr.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventi\",\"item\":\"http:\\\/\\\/www.sma.unipr.it\\\/it\\\/eventi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gran folla al MUST: debutto da record per il Museo di Storiografia Naturalistica dell\u2019Ateneo\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.sma.unipr.it\\\/it\\\/#website\",\"url\":\"http:\\\/\\\/www.sma.unipr.it\\\/it\\\/\",\"name\":\"Sistema Museale di Ateneo\",\"description\":\"Musei Universit\u00e0 di Parma\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.sma.unipr.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.sma.unipr.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/www.sma.unipr.it\\\/it\\\/#organization\",\"name\":\"Sistema Museale di Ateneo\",\"url\":\"http:\\\/\\\/www.sma.unipr.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/www.sma.unipr.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.sma.unipr.it\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/SMA-nero-BANDIERA.png\",\"contentUrl\":\"http:\\\/\\\/www.sma.unipr.it\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/SMA-nero-BANDIERA.png\",\"width\":1910,\"height\":633,\"caption\":\"Sistema Museale di Ateneo\"},\"image\":{\"@id\":\"http:\\\/\\\/www.sma.unipr.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MEMAunipr\\\/\",\"https:\\\/\\\/www.instagram.com\\\/museiunipr\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gran folla al MUST: debutto da record per il Museo di Storiografia Naturalistica dell\u2019Ateneo - Sistema Museale di Ateneo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.sma.unipr.it\/it\/event\/gran-folla-al-must-debutto-da-record-per-il-museo-di-storiografia-naturalistica-dellateneo\/","og_locale":"it_IT","og_type":"article","og_title":"Gran folla al MUST: debutto da record per il Museo di Storiografia Naturalistica dell\u2019Ateneo - Sistema Museale di Ateneo","og_description":"Davvero un gran debutto per il MUST, il\u00a0Museo di Storiografia Naturalistica dell\u2019Universit\u00e0 di Parma. Dopo le prime due giornate solo su prenotazione, oggi l\u2019apertura a ingresso libero \u00e8 stata da [&hellip;]","og_url":"http:\/\/www.sma.unipr.it\/it\/event\/gran-folla-al-must-debutto-da-record-per-il-museo-di-storiografia-naturalistica-dellateneo\/","og_site_name":"Sistema Museale di Ateneo","article_publisher":"https:\/\/www.facebook.com\/MEMAunipr\/","article_modified_time":"2025-11-11T08:12:17+00:00","og_image":[{"width":1030,"height":687,"url":"http:\/\/www.sma.unipr.it\/wp-content\/uploads\/2025\/11\/MUST-wunderkammer-farfalle-imamgine-in-evidenza-1030x687.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.sma.unipr.it\/it\/event\/gran-folla-al-must-debutto-da-record-per-il-museo-di-storiografia-naturalistica-dellateneo\/","url":"http:\/\/www.sma.unipr.it\/it\/event\/gran-folla-al-must-debutto-da-record-per-il-museo-di-storiografia-naturalistica-dellateneo\/","name":"Gran folla al MUST: debutto da record per il Museo di Storiografia Naturalistica dell\u2019Ateneo - Sistema Museale di Ateneo","isPartOf":{"@id":"http:\/\/www.sma.unipr.it\/it\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.sma.unipr.it\/it\/event\/gran-folla-al-must-debutto-da-record-per-il-museo-di-storiografia-naturalistica-dellateneo\/#primaryimage"},"image":{"@id":"http:\/\/www.sma.unipr.it\/it\/event\/gran-folla-al-must-debutto-da-record-per-il-museo-di-storiografia-naturalistica-dellateneo\/#primaryimage"},"thumbnailUrl":"http:\/\/www.sma.unipr.it\/wp-content\/uploads\/2025\/11\/MUST-wunderkammer-farfalle-imamgine-in-evidenza.png","datePublished":"2025-11-03T09:32:01+00:00","dateModified":"2025-11-11T08:12:17+00:00","breadcrumb":{"@id":"http:\/\/www.sma.unipr.it\/it\/event\/gran-folla-al-must-debutto-da-record-per-il-museo-di-storiografia-naturalistica-dellateneo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.sma.unipr.it\/it\/event\/gran-folla-al-must-debutto-da-record-per-il-museo-di-storiografia-naturalistica-dellateneo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.sma.unipr.it\/it\/event\/gran-folla-al-must-debutto-da-record-per-il-museo-di-storiografia-naturalistica-dellateneo\/#primaryimage","url":"http:\/\/www.sma.unipr.it\/wp-content\/uploads\/2025\/11\/MUST-wunderkammer-farfalle-imamgine-in-evidenza.png","contentUrl":"http:\/\/www.sma.unipr.it\/wp-content\/uploads\/2025\/11\/MUST-wunderkammer-farfalle-imamgine-in-evidenza.png","width":1200,"height":800,"caption":"MUST wunderkammer"},{"@type":"BreadcrumbList","@id":"http:\/\/www.sma.unipr.it\/it\/event\/gran-folla-al-must-debutto-da-record-per-il-museo-di-storiografia-naturalistica-dellateneo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.sma.unipr.it\/it\/"},{"@type":"ListItem","position":2,"name":"Eventi","item":"http:\/\/www.sma.unipr.it\/it\/eventi\/"},{"@type":"ListItem","position":3,"name":"Gran folla al MUST: debutto da record per il Museo di Storiografia Naturalistica dell\u2019Ateneo"}]},{"@type":"WebSite","@id":"http:\/\/www.sma.unipr.it\/it\/#website","url":"http:\/\/www.sma.unipr.it\/it\/","name":"Sistema Museale di Ateneo","description":"Musei Universit\u00e0 di Parma","publisher":{"@id":"http:\/\/www.sma.unipr.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.sma.unipr.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"http:\/\/www.sma.unipr.it\/it\/#organization","name":"Sistema Museale di Ateneo","url":"http:\/\/www.sma.unipr.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/www.sma.unipr.it\/it\/#\/schema\/logo\/image\/","url":"http:\/\/www.sma.unipr.it\/wp-content\/uploads\/2023\/10\/SMA-nero-BANDIERA.png","contentUrl":"http:\/\/www.sma.unipr.it\/wp-content\/uploads\/2023\/10\/SMA-nero-BANDIERA.png","width":1910,"height":633,"caption":"Sistema Museale di Ateneo"},"image":{"@id":"http:\/\/www.sma.unipr.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MEMAunipr\/","https:\/\/www.instagram.com\/museiunipr\/"]}]}},"_links":{"self":[{"href":"http:\/\/www.sma.unipr.it\/it\/wp-json\/wp\/v2\/tribe_events\/44205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.sma.unipr.it\/it\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"http:\/\/www.sma.unipr.it\/it\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"http:\/\/www.sma.unipr.it\/it\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":6,"href":"http:\/\/www.sma.unipr.it\/it\/wp-json\/wp\/v2\/tribe_events\/44205\/revisions"}],"predecessor-version":[{"id":44336,"href":"http:\/\/www.sma.unipr.it\/it\/wp-json\/wp\/v2\/tribe_events\/44205\/revisions\/44336"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.sma.unipr.it\/it\/wp-json\/wp\/v2\/media\/44222"}],"wp:attachment":[{"href":"http:\/\/www.sma.unipr.it\/it\/wp-json\/wp\/v2\/media?parent=44205"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.sma.unipr.it\/it\/wp-json\/wp\/v2\/tags?post=44205"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"http:\/\/www.sma.unipr.it\/it\/wp-json\/wp\/v2\/tribe_events_cat?post=44205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}