﻿{"id":6671,"date":"2020-06-04T16:24:02","date_gmt":"2020-06-04T14:24:02","guid":{"rendered":"http:\/\/www.sma.unipr.it\/?page_id=6671"},"modified":"2026-07-10T11:12:58","modified_gmt":"2026-07-10T09:12:58","slug":"organizza-la-tua-visita","status":"publish","type":"page","link":"https:\/\/www.sma.unipr.it\/it\/museo-diffuso-delle-scienze\/collezione-di-cristallochimica\/organizza-la-tua-visita\/","title":{"rendered":"Organizza la tua visita"},"content":{"rendered":"<div id='full_slider_1'  class='avia-fullwidth-slider main_color avia-shadow   avia-builder-el-0  el_before_av_one_full  avia-builder-el-first   container_wrap fullsize'  ><div  class='avia-slideshow av-kccbbdlv-8b2bc777a184b4672d11215bba103ee2 avia-slideshow-featured_large av_slideshow_full avia-slide-slider av-slideshow-ui av-control-default av-slideshow-manual av-loop-once av-loop-manual-endless av-default-height-applied   avia-slideshow-1' data-slideshow-options=\"{&quot;animation&quot;:&quot;slide&quot;,&quot;autoplay&quot;:false,&quot;loop_autoplay&quot;:&quot;once&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:false,&quot;hoverpause&quot;:false,&quot;show_slide_delay&quot;:0}\"  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><ul class='avia-slideshow-inner ' style='padding-bottom: 64.412070759625%;'><li  class='avia-slideshow-slide av-kccbbdlv-8b2bc777a184b4672d11215bba103ee2__0  av-single-slide slide-1 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><div class='av-slideshow-caption av-kccbbdlv-8b2bc777a184b4672d11215bba103ee2__0 caption_fullwidth caption_center caption_center_framed caption_framed'><div class=\"container caption_container\"><div class=\"slideshow_caption\"><div class=\"slideshow_inner_caption\"><div class=\"slideshow_align_caption\"><h2 class='avia-caption-title '  itemprop=\"name\" >ORGANIZZA LA TUA VISITA<\/h2><\/div><\/div><\/div><\/div><\/div><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-7990 avia-img-lazy-loading-not-7990\"  src=\"https:\/\/www.sma.unipr.it\/wp-content\/uploads\/2020\/07\/QuarzoMaderaIMMAGINE-PER-SLIDE-ALTA.jpg\" width=\"961\" height=\"619\" title='QuarzoMaderaIMMAGINE PER SLIDE ALTA' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.sma.unipr.it\/wp-content\/uploads\/2020\/07\/QuarzoMaderaIMMAGINE-PER-SLIDE-ALTA.jpg 961w, https:\/\/www.sma.unipr.it\/wp-content\/uploads\/2020\/07\/QuarzoMaderaIMMAGINE-PER-SLIDE-ALTA-300x193.jpg 300w, https:\/\/www.sma.unipr.it\/wp-content\/uploads\/2020\/07\/QuarzoMaderaIMMAGINE-PER-SLIDE-ALTA-768x495.jpg 768w, https:\/\/www.sma.unipr.it\/wp-content\/uploads\/2020\/07\/QuarzoMaderaIMMAGINE-PER-SLIDE-ALTA-705x454.jpg 705w, https:\/\/www.sma.unipr.it\/wp-content\/uploads\/2020\/07\/QuarzoMaderaIMMAGINE-PER-SLIDE-ALTA-450x290.jpg 450w\" sizes=\"(max-width: 961px) 100vw, 961px\" \/><\/div><\/li><\/ul><\/div><\/div><div id='after_full_slider_1'  class='main_color av_default_container_wrap container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-6671'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-23smgf-5e82c400add0edb37a1564b956e3675f\">\n.flex_column.av-23smgf-5e82c400add0edb37a1564b956e3675f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-23smgf-5e82c400add0edb37a1564b956e3675f av_one_full  avia-builder-el-1  el_after_av_slideshow_full  el_before_av_section  avia-builder-el-no-sibling  first flex_column_div av-zero-column-padding  '     ><p><article  class='iconbox iconbox_top av-mrepv337-cb4f1bb4c978d2c5098dbcd207a5d894  avia-builder-el-2  el_before_av_icon_box  avia-builder-el-first  main_color'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icona: Chiusura estiva\"><div class='iconbox_icon heading-color avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='info' data-av_iconset='svg_entypo-fontello' ><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"32\" viewBox=\"0 0 15 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-1' aria-describedby='av-svg-desc-1' role=\"graphics-symbol\">\n<title id='av-svg-title-1'>Info<\/title>\n<desc id='av-svg-desc-1'>Info<\/desc>\n<path d=\"M11.264 0q1.536 0 2.368 0.864t0.832 2.208q0 1.6-1.248 2.816t-3.040 1.216q-1.536 0-2.368-0.832t-0.768-2.304q0-1.472 1.12-2.72t3.104-1.248zM4.672 32q-3.2 0-1.728-5.696l1.92-8.128q0.448-1.792 0-1.792-0.384 0-1.728 0.576t-2.304 1.216l-0.832-1.408q2.88-2.496 6.048-4.032t4.832-1.536q2.496 0 1.152 5.184l-2.24 8.512q-0.512 2.048 0.192 2.048 1.408 0 3.776-1.92l0.96 1.28q-2.688 2.752-5.6 4.224t-4.448 1.472z\"><\/path>\n<\/svg><\/div><h3 class='iconbox_content_title '  itemprop=\"headline\" >Chiusura estiva<\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><p>La Collezione di Cristallochimica sar\u00e0 chiusa dal 4 al 24 agosto.<\/p>\n<p>Riapertura regolare da marted\u00ec 25 agosto.<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><br \/>\n<article  class='iconbox iconbox_top av-knyfk4dz-d885ac3500a56c62455427c9297a6d13  avia-builder-el-3  el_after_av_icon_box  avia-builder-el-last  main_color'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icona: La COLLEZIONE DI CRISTALLOCHIMICA \u00e8 visitabile \"><div class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue81e' data-av_iconfont='entypo-fontello'  ><\/div><h3 class='iconbox_content_title '  itemprop=\"headline\" >La COLLEZIONE DI CRISTALLOCHIMICA \u00e8 visitabile <\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><p style=\"text-align: center;\">La visita individuale e di gruppo va prenotata,\u00a0con almeno 3 giorni di anticipo, utilizzando il\u00a0<a href=\"http:\/\/www.sma.unipr.it\/it\/museo-diffuso-delle-scienze\/collezione-di-cristallochimica\/collezione-di-cristallochimica-prenotazione-visite-individuali-e-di-gruppo\/\">modulo online per le visite individuali e di gruppo<\/a>.<\/p>\n<p style=\"text-align: center;\">La visita per le scuole va prenotata,\u00a0con almeno 3 giorni di anticipo, utilizzando il\u00a0<a href=\"http:\/\/www.sma.unipr.it\/it\/collezione-di-cristallochimica-prenotazione-per-le-scuole\/\">modulo online per le visite per le scuole<\/a>.<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/p><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kccb5xsg-3a4656e13640b906bb6233e1d017e07c\">\n.avia-section.av-kccb5xsg-3a4656e13640b906bb6233e1d017e07c{\nbackground-color:#f9f9f9;\nbackground-image:unset;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-kccb5xsg-3a4656e13640b906bb6233e1d017e07c main_color avia-section-default avia-no-border-styling  avia-builder-el-4  el_after_av_one_full  el_before_av_google_map  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-6671'><div class='entry-content-wrapper clearfix'>\n<section  class='av_textblock_section av-kb0veo7o-f18cd582f12872a8e4b5ee58cf855fcc '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><strong>ORARI DI APERTURA<\/strong><\/p>\n<p>Da marted\u00ec a venerd\u00ec ore 9.00 \u2013 18.00<br \/>\nEntrata gratuita<br \/>\nVisite guidate per scolaresche e gruppi su prenotazione.<br \/>\n<strong>Chiusura estiva: dal 4 al 24 agosto 2026. Riapertura regolare da marted\u00ec 25 agosto.<\/strong><\/p>\n<p><b>DOVE SIAMO<\/b><\/p>\n<p>Plesso Chimico<br \/>\nParco Area delle Scienze, 17\/A &#8211; 43124 Parma<br \/>\nTel. + 39 0521 905432 &#8211; Fax + 39 0521 905557<br \/>\ne-mail:\u00a0<a href=\"mailto:museo.cristalli@unipr.it\">museo.cristalli@unipr.it<\/a><\/p>\n<p><strong>COME RAGGIUNGERCI<\/strong><\/p>\n<p>In auto: A1 uscita Parma, Tangenziale uscita 15, a destra Campus, prima a destra,<br \/>\nterzo edificio a sinistra. Parcheggio riservato\u00a0ai visitatori<br \/>\nIn treno: stazione di Parma<br \/>\nIn autobus: n\u00a0<a href=\"https:\/\/www.tep.pr.it\/linee-e-orari\/linee-urbane\/\">7 &#8211;\u00a0 21 &#8211; Campus express<\/a><\/p>\n<\/div><\/section>\n<\/p>\n<div  class='av_gmaps_sc_main_wrap av_gmaps_main_wrap '><div id='av_gmap_0' class='avia-google-map-container avia-google-map-sc av_gmaps_show_unconditionally av-no-fallback-img ' data-mapid='av_gmap_0'  style='height: 400px;'><a class=\"av_gmaps_browser_disabled av_text_confirm_link av_text_confirm_link_visible\" href=\"https:\/\/www.google.com\/maps\/search\/?api=1&#038;query=Parco%20Area%20delle%20Scienze,%2017\/A%2040124%20Parma%20Italia%20Italia\" target=\"_blank\">Le mappe sono state disabilitate dal visitatore di questo sito. Clicca per aprire la mappa in una nuova finestra.<\/a><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":338,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6671","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Organizza la tua visita - Sistema Museale di Ateneo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sma.unipr.it\/it\/museo-diffuso-delle-scienze\/collezione-di-cristallochimica\/organizza-la-tua-visita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Organizza la tua visita - Sistema Museale di Ateneo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sma.unipr.it\/it\/museo-diffuso-delle-scienze\/collezione-di-cristallochimica\/organizza-la-tua-visita\/\" \/>\n<meta property=\"og:site_name\" content=\"Sistema Museale di Ateneo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MEMAunipr\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T09:12:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sma.unipr.it\\\/it\\\/museo-diffuso-delle-scienze\\\/collezione-di-cristallochimica\\\/organizza-la-tua-visita\\\/\",\"url\":\"https:\\\/\\\/www.sma.unipr.it\\\/it\\\/museo-diffuso-delle-scienze\\\/collezione-di-cristallochimica\\\/organizza-la-tua-visita\\\/\",\"name\":\"Organizza la tua visita - Sistema Museale di Ateneo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sma.unipr.it\\\/it\\\/#website\"},\"datePublished\":\"2020-06-04T14:24:02+00:00\",\"dateModified\":\"2026-07-10T09:12:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sma.unipr.it\\\/it\\\/museo-diffuso-delle-scienze\\\/collezione-di-cristallochimica\\\/organizza-la-tua-visita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sma.unipr.it\\\/it\\\/museo-diffuso-delle-scienze\\\/collezione-di-cristallochimica\\\/organizza-la-tua-visita\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sma.unipr.it\\\/it\\\/museo-diffuso-delle-scienze\\\/collezione-di-cristallochimica\\\/organizza-la-tua-visita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sma.unipr.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Museo Diffuso delle Scienze\",\"item\":\"https:\\\/\\\/www.sma.unipr.it\\\/it\\\/museo-diffuso-delle-scienze\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Collezione di Cristallochimica\",\"item\":\"https:\\\/\\\/www.sma.unipr.it\\\/it\\\/museo-diffuso-delle-scienze\\\/collezione-di-cristallochimica\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Organizza la tua visita\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sma.unipr.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.sma.unipr.it\\\/it\\\/\",\"name\":\"Sistema Museale di Ateneo\",\"description\":\"Musei Universit\u00e0 di Parma\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sma.unipr.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sma.unipr.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sma.unipr.it\\\/it\\\/#organization\",\"name\":\"Sistema Museale di Ateneo\",\"url\":\"https:\\\/\\\/www.sma.unipr.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.sma.unipr.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/www.sma.unipr.it\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/SMA-nero-BANDIERA.png\",\"contentUrl\":\"http:\\\/\\\/www.sma.unipr.it\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/SMA-nero-BANDIERA.png\",\"width\":1910,\"height\":633,\"caption\":\"Sistema Museale di Ateneo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sma.unipr.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MEMAunipr\\\/\",\"https:\\\/\\\/www.instagram.com\\\/museiunipr\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Organizza la tua visita - Sistema Museale di Ateneo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sma.unipr.it\/it\/museo-diffuso-delle-scienze\/collezione-di-cristallochimica\/organizza-la-tua-visita\/","og_locale":"it_IT","og_type":"article","og_title":"Organizza la tua visita - Sistema Museale di Ateneo","og_url":"https:\/\/www.sma.unipr.it\/it\/museo-diffuso-delle-scienze\/collezione-di-cristallochimica\/organizza-la-tua-visita\/","og_site_name":"Sistema Museale di Ateneo","article_publisher":"https:\/\/www.facebook.com\/MEMAunipr\/","article_modified_time":"2026-07-10T09:12:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sma.unipr.it\/it\/museo-diffuso-delle-scienze\/collezione-di-cristallochimica\/organizza-la-tua-visita\/","url":"https:\/\/www.sma.unipr.it\/it\/museo-diffuso-delle-scienze\/collezione-di-cristallochimica\/organizza-la-tua-visita\/","name":"Organizza la tua visita - Sistema Museale di Ateneo","isPartOf":{"@id":"https:\/\/www.sma.unipr.it\/it\/#website"},"datePublished":"2020-06-04T14:24:02+00:00","dateModified":"2026-07-10T09:12:58+00:00","breadcrumb":{"@id":"https:\/\/www.sma.unipr.it\/it\/museo-diffuso-delle-scienze\/collezione-di-cristallochimica\/organizza-la-tua-visita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sma.unipr.it\/it\/museo-diffuso-delle-scienze\/collezione-di-cristallochimica\/organizza-la-tua-visita\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sma.unipr.it\/it\/museo-diffuso-delle-scienze\/collezione-di-cristallochimica\/organizza-la-tua-visita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sma.unipr.it\/it\/"},{"@type":"ListItem","position":2,"name":"Museo Diffuso delle Scienze","item":"https:\/\/www.sma.unipr.it\/it\/museo-diffuso-delle-scienze\/"},{"@type":"ListItem","position":3,"name":"Collezione di Cristallochimica","item":"https:\/\/www.sma.unipr.it\/it\/museo-diffuso-delle-scienze\/collezione-di-cristallochimica\/"},{"@type":"ListItem","position":4,"name":"Organizza la tua visita"}]},{"@type":"WebSite","@id":"https:\/\/www.sma.unipr.it\/it\/#website","url":"https:\/\/www.sma.unipr.it\/it\/","name":"Sistema Museale di Ateneo","description":"Musei Universit\u00e0 di Parma","publisher":{"@id":"https:\/\/www.sma.unipr.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sma.unipr.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.sma.unipr.it\/it\/#organization","name":"Sistema Museale di Ateneo","url":"https:\/\/www.sma.unipr.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.sma.unipr.it\/it\/#\/schema\/logo\/image\/","url":"http:\/\/www.sma.unipr.it\/wp-content\/uploads\/2023\/10\/SMA-nero-BANDIERA.png","contentUrl":"http:\/\/www.sma.unipr.it\/wp-content\/uploads\/2023\/10\/SMA-nero-BANDIERA.png","width":1910,"height":633,"caption":"Sistema Museale di Ateneo"},"image":{"@id":"https:\/\/www.sma.unipr.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MEMAunipr\/","https:\/\/www.instagram.com\/museiunipr\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.sma.unipr.it\/it\/wp-json\/wp\/v2\/pages\/6671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sma.unipr.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sma.unipr.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sma.unipr.it\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sma.unipr.it\/it\/wp-json\/wp\/v2\/comments?post=6671"}],"version-history":[{"count":82,"href":"https:\/\/www.sma.unipr.it\/it\/wp-json\/wp\/v2\/pages\/6671\/revisions"}],"predecessor-version":[{"id":46636,"href":"https:\/\/www.sma.unipr.it\/it\/wp-json\/wp\/v2\/pages\/6671\/revisions\/46636"}],"up":[{"embeddable":true,"href":"https:\/\/www.sma.unipr.it\/it\/wp-json\/wp\/v2\/pages\/338"}],"wp:attachment":[{"href":"https:\/\/www.sma.unipr.it\/it\/wp-json\/wp\/v2\/media?parent=6671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}